{"id":12082,"date":"2026-05-12T11:15:00","date_gmt":"2026-05-12T15:15:00","guid":{"rendered":"https:\/\/desdelsurnoticias.com\/index.php\/2026\/05\/12\/fiscalia-ratifica-que-pedira-20-anos-de-carcel-para-evo-morales\/"},"modified":"2026-05-12T11:15:00","modified_gmt":"2026-05-12T15:15:00","slug":"fiscalia-ratifica-que-pedira-20-anos-de-carcel-para-evo-morales","status":"publish","type":"post","link":"https:\/\/desdelsurnoticias.com\/index.php\/2026\/05\/12\/fiscalia-ratifica-que-pedira-20-anos-de-carcel-para-evo-morales\/","title":{"rendered":"Fiscal\u00eda ratifica que pedir\u00e1 20 a\u00f1os de c\u00e1rcel para Evo Morales"},"content":{"rendered":"<p>El expresidente Morales no se present\u00f3 el lunes al inicio de su juicio oral por supuesta trata de personas con agravante.<\/p>\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/hub.idealabgroup.com\/public\/uploads\/img_dbe3dad3b7a2428fa90ef87fefb4fa1c703c5759.webp\" alt=\"El expresidente Evo Morales.\"\/><figcaption>El expresidente Evo Morales.<\/figcaption><\/figure>\n<p>&nbsp;El Ministerio P\u00fablico solicitar\u00e1 20 a\u00f1os de c\u00e1rcel para el expresidente Evo Morales&nbsp;en su juicio por la presunta comisi\u00f3n del delito de trata de personas con agravante, confirm\u00f3 este martes el fiscal departamental de Tarija, Jos\u00e9 Ernesto Mogro Palacios.<\/p>\n<p>\u201cEl Art\u00edculo 281 bis del C\u00f3digo Penal nos habla del delito de trata de personas agravada. Es decir, (cuando se tiene) una v\u00edctima menor de edad, se agrava la situaci\u00f3n y la pena m\u00e1xima es de 20 a\u00f1os de presidio, y eso es lo que el Ministerio P\u00fablico, luego de producir su prueba y demostrar su teor\u00eda del hecho, va a solicitar\u201d, dijo el fiscal en el programa&nbsp;A Primera Hora de ED24.&nbsp;<\/p>\n<p>El exmandatario corre este riesgo por la&nbsp;relaci\u00f3n que habr\u00eda tenido con una menor de edad cuando era presidente del Estado, llegando a tener incluso una hija&nbsp;con su v\u00edctima.&nbsp;&nbsp;Mogro Palacios record\u00f3 que se ten\u00eda programado, para el pasado lunes 11 de mayo, el inicio del juicio oral en contra de Morales y de la coacusada Idelsa Pozo Saavedra, madre de la v\u00edctima, pero ninguno se present\u00f3 \u201cni ha justificado, de manera adecuada, su inasistencia\u201d.<\/p>\n<p>Ante esa situaci\u00f3n, \u201cel Ministerio P\u00fablico ha solicitado que se declare la rebeld\u00eda, pedido que ha sido escuchado por el Tribunal Primero de Sentencia de Tarija (\u2026) y&nbsp;se emiti\u00f3 el respectivo mandamiento de aprehensi\u00f3n, (adem\u00e1s de la) orden de&nbsp;arraigo&nbsp;de las dos personas, como tambi\u00e9n el&nbsp;congelamiento de sus cuentas\u201d, detall\u00f3.&nbsp;<\/p>\n<p>Ahora, seg\u00fan remarc\u00f3 el fiscal, la Polic\u00eda debe ejecutar el mandamiento de aprehensi\u00f3n en cumplimiento de su mandato constitucional.<\/p>\n<p>Sin embargo, cada vez que se emite mandamientos de aprehensi\u00f3n en contra de Morales no se ejecuta porque el exmandatario vive refugiado en el Tr\u00f3pico de Cochabamba con el resguardo permanente de sus seguidores.<\/p>","protected":false},"excerpt":{"rendered":"<p>El expresidente Morales no se present\u00f3 el lunes al inicio de su juicio oral por supuesta trata de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/hub.idealabgroup.com\/public\/uploads\/img_dbe3dad3b7a2428fa90ef87fefb4fa1c703c5759.webp","fifu_image_alt":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-12082","post","type-post","status-publish","format-standard","hentry","category-tarija"],"_links":{"self":[{"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/12082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=12082"}],"version-history":[{"count":0,"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/12082\/revisions"}],"wp:attachment":[{"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=12082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=12082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desdelsurnoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=12082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}